{"id":2378,"date":"2026-06-29T15:24:17","date_gmt":"2026-06-29T15:24:17","guid":{"rendered":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/?p=2378"},"modified":"2026-06-29T15:24:19","modified_gmt":"2026-06-29T15:24:19","slug":"curso-teorico-practico-avanzado-ecografia-del-nervio-periferico-lleida","status":"publish","type":"post","link":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/curso-teorico-practico-avanzado-ecografia-del-nervio-periferico-lleida\/","title":{"rendered":"Curso te\u00f3rico-pr\u00e1ctico avanzado: Ecograf\u00eda del nervio perif\u00e9rico en Lleida"},"content":{"rendered":"\n<div class=\"wp-block-media-text is-stacked-on-mobile has-vivid-red-background-color has-background\" style=\"grid-template-columns:35% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/enovis-medtech.eu\/es_ES\/blog\/wp-content\/uploads\/2026\/03\/Imagen-de-WhatsApp-2025-11-17-a-las-10.30.14_f0dd332b-1024x768.jpg\" alt=\"\" class=\"wp-image-2204 size-full\" srcset=\"https:\/\/enovis-medtech.eu\/es_ES\/blog\/wp-content\/uploads\/2026\/03\/Imagen-de-WhatsApp-2025-11-17-a-las-10.30.14_f0dd332b-1024x768.jpg 1024w, https:\/\/enovis-medtech.eu\/es_ES\/blog\/wp-content\/uploads\/2026\/03\/Imagen-de-WhatsApp-2025-11-17-a-las-10.30.14_f0dd332b-300x225.jpg 300w, https:\/\/enovis-medtech.eu\/es_ES\/blog\/wp-content\/uploads\/2026\/03\/Imagen-de-WhatsApp-2025-11-17-a-las-10.30.14_f0dd332b-768x576.jpg 768w, https:\/\/enovis-medtech.eu\/es_ES\/blog\/wp-content\/uploads\/2026\/03\/Imagen-de-WhatsApp-2025-11-17-a-las-10.30.14_f0dd332b-1536x1152.jpg 1536w, https:\/\/enovis-medtech.eu\/es_ES\/blog\/wp-content\/uploads\/2026\/03\/Imagen-de-WhatsApp-2025-11-17-a-las-10.30.14_f0dd332b.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-text-align-center has-white-color has-vivid-red-background-color has-text-color has-background has-link-color wp-elements-c25d16d784f3c9cfb1f9ea4276003ce4 wp-block-paragraph\"><strong>Fecha de inicio:<\/strong> <br>5 y 6 de septiembre de 2026.<br><strong>Poblaci\u00f3n: <\/strong><br>Lleida<br><strong>Lugar de realizaci\u00f3n:<\/strong> <br>Hotel Zenit Lleida<br><strong>Horario: <\/strong><br>S\u00e1bado de 9h a 14h y de 15h a 20h. Domingo de 9h a 14h<br><strong>Duraci\u00f3n:<\/strong> 15h.<br><strong>Precio: <\/strong>200\u20ac<\/p>\n<\/div><\/div>\n\n\n\n<div style=\"height:78px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Con la colaboraci\u00f3n de:<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"343\" src=\"https:\/\/enovis-medtech.eu\/es_ES\/blog\/wp-content\/uploads\/2026\/03\/cfc-logotip-alternativa-2-cmyk-1024x343.png\" alt=\"\" class=\"wp-image-2213\" style=\"aspect-ratio:2.98550563669684;width:296px;height:auto\" srcset=\"https:\/\/enovis-medtech.eu\/es_ES\/blog\/wp-content\/uploads\/2026\/03\/cfc-logotip-alternativa-2-cmyk-1024x343.png 1024w, https:\/\/enovis-medtech.eu\/es_ES\/blog\/wp-content\/uploads\/2026\/03\/cfc-logotip-alternativa-2-cmyk-300x100.png 300w, https:\/\/enovis-medtech.eu\/es_ES\/blog\/wp-content\/uploads\/2026\/03\/cfc-logotip-alternativa-2-cmyk-768x257.png 768w, https:\/\/enovis-medtech.eu\/es_ES\/blog\/wp-content\/uploads\/2026\/03\/cfc-logotip-alternativa-2-cmyk.png 1040w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:56px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link has-vivid-red-background-color has-background wp-element-button\" href=\"https:\/\/www.chattanoogarehab.com\/es\/curso-te-rico-pr-ctico-avanzado-de-ecograf-a-del-nervio-perif-rico-mrkesform35-es\" target=\"_blank\" rel=\"noreferrer noopener\">Inscribirme<\/a><\/div>\n<\/div>\n\n\n\n<p class=\"has-text-align-center has-small-font-size wp-block-paragraph\"><sub>*Al presionar el bot\u00f3n te redirigiremos a nuestra p\u00e1gina chattanoogarehab.com para realizar tu inscripci\u00f3n. <\/sub><\/p>\n\n\n\n<div style=\"height:47px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center has-large-font-size\"><strong>\u00bfQu\u00e9 aprender\u00e1s en esta formaci\u00f3n?<\/strong><\/h2>\n\n\n\n<div style=\"height:47px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-left has-medium-font-size wp-block-paragraph\">El curso avanzado: \u00abEcograf\u00eda del nervio perif\u00e9rico\u00bb en Lleida est\u00e1 dise\u00f1ado para ofrecer a los participantes una introducci\u00f3n completa a la sonoanatom\u00eda del nervio perif\u00e9rico, con un enfoque pr\u00e1ctico y cl\u00ednico. Durante los dos d\u00edas de duraci\u00f3n de la formaci\u00f3n, los alumnos aprender\u00e1n a identificar los principales nervios de las extremidades superiores e inferiores, as\u00ed como las interfases anat\u00f3micas y las patolog\u00edas que pueden afectarles.<\/p>\n\n\n\n<p class=\"has-text-align-left has-medium-font-size wp-block-paragraph\"><\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center has-large-font-size\"><strong>Contenidos el curso<\/strong><\/h2>\n\n\n\n<div style=\"height:47px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size wp-block-paragraph\">Introducci\u00f3n a la sonoanatom\u00eda del nervio perif\u00e9rico.<br>Recorrido por las principales interfases de los nervios de la extremidad superior: <em>nervio mediano, nervio cubital, nervio radial, nervio axilar y nervio supraescapular<\/em><br>Recorrido y principales interfases de los nervios de la extremidad inferior: <em>nervio femara-cut\u00e1neo lateral, nervio femoral, nervio safeno, nervio obturador, nervio ci\u00e1tico, nervio tibial, nervio peroneal com\u00fan, nervio peroneal superficial y nervio peroneal profundo<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size wp-block-paragraph\"><\/p>\n\n\n\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center has-large-font-size\"><strong>Ponente<\/strong><\/h2>\n\n\n\n<div style=\"height:47px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\"><div class=\"wp-block-image is-style-rounded\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1706\" height=\"2560\" src=\"https:\/\/enovis-medtech.eu\/es_ES\/blog\/wp-content\/uploads\/2025\/01\/Sergio-Romero-2025.jpeg\" alt=\"Sergio Romero, ponente del curso de Actualizaci\u00f3n en tendinopat\u00eda rotuliana\" class=\"wp-image-788\" style=\"aspect-ratio:1;object-fit:cover;width:268px\" srcset=\"https:\/\/enovis-medtech.eu\/es_ES\/blog\/wp-content\/uploads\/2025\/01\/Sergio-Romero-2025.jpeg 1706w, https:\/\/enovis-medtech.eu\/es_ES\/blog\/wp-content\/uploads\/2025\/01\/Sergio-Romero-2025-200x300.jpeg 200w, https:\/\/enovis-medtech.eu\/es_ES\/blog\/wp-content\/uploads\/2025\/01\/Sergio-Romero-2025-682x1024.jpeg 682w, https:\/\/enovis-medtech.eu\/es_ES\/blog\/wp-content\/uploads\/2025\/01\/Sergio-Romero-2025-768x1152.jpeg 768w, https:\/\/enovis-medtech.eu\/es_ES\/blog\/wp-content\/uploads\/2025\/01\/Sergio-Romero-2025-1024x1536.jpeg 1024w, https:\/\/enovis-medtech.eu\/es_ES\/blog\/wp-content\/uploads\/2025\/01\/Sergio-Romero-2025-1365x2048.jpeg 1365w\" sizes=\"auto, (max-width: 1706px) 100vw, 1706px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h3 class=\"wp-block-heading has-text-align-center has-medium-font-size\">Sergio Romero<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size wp-block-paragraph\">Fisioterapeuta n\u00ba col. 9637, Experto en lesiones musculares y tendinosas, Consultor externo de deportistas profesionales, CEO CR Fisioterapia.<br><\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center has-large-font-size\"><strong>Precio<\/strong><\/h2>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-large-font-size wp-block-paragraph\"><strong>200\u20ac<\/strong><\/p>\n\n\n\n<div style=\"height:29px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link has-vivid-red-background-color has-background wp-element-button\" href=\"https:\/\/www.chattanoogarehab.com\/es\/curso-te-rico-pr-ctico-avanzado-de-ecograf-a-del-nervio-perif-rico-mrkesform35-es\" target=\"_blank\" rel=\"noreferrer noopener\">Inscribirme<\/a><\/div>\n<\/div>\n\n\n\n<p class=\"has-text-align-center has-small-font-size wp-block-paragraph\"><sub>*Al presionar el bot\u00f3n te redirigiremos a nuestra p\u00e1gina chattanoogarehab.com para realizar tu inscripci\u00f3n. <\/sub><\/p>\n\n\n\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center has-large-font-size\"><strong>Ubicaci\u00f3n<\/strong><\/h2>\n\n\n\n<div style=\"height:49px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-content-justification-center is-nowrap is-layout-flex wp-container-core-group-is-layout-d05cb3ef wp-block-group-is-layout-flex\">\n<h3 class=\"wp-block-heading has-text-align-center\">Hotel Zenit<\/h3>\n<\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Carrer General Brito, 21, 25007 Lleida<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-stretch is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-gmap-gmap-block gmap-block-gpujggok\"><iframe src=\"https:\/\/maps.google.com\/maps?q=Hotel+Zenit+Lleida&amp;z=11&amp;t=roadmap&amp;output=embed\" class=\"embd-map\" title=\"Hotel Zenit Lleida\"><\/iframe><\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:142px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>Orgullosos colaboradores<\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"300\" src=\"https:\/\/enovis-medtech.eu\/es_ES\/blog\/wp-content\/uploads\/2026\/05\/Proveedor-Federaciones_sin-fondo.png\" alt=\"\" class=\"wp-image-2372\" style=\"width:768px;height:auto\" srcset=\"https:\/\/enovis-medtech.eu\/es_ES\/blog\/wp-content\/uploads\/2026\/05\/Proveedor-Federaciones_sin-fondo.png 1200w, https:\/\/enovis-medtech.eu\/es_ES\/blog\/wp-content\/uploads\/2026\/05\/Proveedor-Federaciones_sin-fondo-300x75.png 300w, https:\/\/enovis-medtech.eu\/es_ES\/blog\/wp-content\/uploads\/2026\/05\/Proveedor-Federaciones_sin-fondo-1024x256.png 1024w, https:\/\/enovis-medtech.eu\/es_ES\/blog\/wp-content\/uploads\/2026\/05\/Proveedor-Federaciones_sin-fondo-768x192.png 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El curso avanzado: \u00abEcograf\u00eda del nervio perif\u00e9rico\u00bb en Lleida est\u00e1 dise\u00f1ado para ofrecer a los participantes una introducci\u00f3n completa a la sonoanatom\u00eda del nervio perif\u00e9rico, con un enfoque pr\u00e1ctico y cl\u00ednico.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[19,18],"tags":[],"class_list":["post-2378","post","type-post","status-publish","format-standard","hentry","category-ecografia","category-formacion"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Curso avanzado: Ecograf\u00eda del nervio perif\u00e9rico en Lleida<\/title>\n<meta name=\"description\" content=\"Curso avanzado: Ecograf\u00eda del nervio perif\u00e9rico en Lleida para mejorar tu diagn\u00f3stico cl\u00ednico con un enfoque pr\u00e1ctico y basado en evidencia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/enovis-medtech.eu\/es_ES\/blog\/curso-teorico-practico-avanzado-ecografia-del-nervio-periferico-lleida\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Curso avanzado en ecograf\u00eda del nervio perif\u00e9rico en Lleida\" \/>\n<meta property=\"og:description\" content=\"Curso te\u00f3rico-pr\u00e1ctico avanzado: Ecograf\u00eda del nervio perif\u00e9rico en Lleida para profesionales que buscan mejorar tu diagn\u00f3stico cl\u00ednico con un enfoque pr\u00e1ctico y basado en evidencia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/enovis-medtech.eu\/es_ES\/blog\/curso-teorico-practico-avanzado-ecografia-del-nervio-periferico-lleida\/\" \/>\n<meta property=\"og:site_name\" content=\"Enovis | Blog en Espa\u00f1ol\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-29T15:24:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-29T15:24:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/enovis-medtech.eu\/es_ES\/blog\/wp-content\/uploads\/2026\/03\/Thumbnail.png\" \/>\n\t<meta property=\"og:image:width\" content=\"350\" \/>\n\t<meta property=\"og:image:height\" content=\"220\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Enovis Ib\u00e9rica\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Enovis Ib\u00e9rica\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/enovis-medtech.eu\\\/es_ES\\\/blog\\\/curso-teorico-practico-avanzado-ecografia-del-nervio-periferico-lleida\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/enovis-medtech.eu\\\/es_ES\\\/blog\\\/curso-teorico-practico-avanzado-ecografia-del-nervio-periferico-lleida\\\/\"},\"author\":{\"name\":\"Enovis Ib\u00e9rica\",\"@id\":\"https:\\\/\\\/enovis-medtech.eu\\\/es_ES\\\/blog\\\/#\\\/schema\\\/person\\\/a2f1e898e8a22c9e2e223732bdcfcf93\"},\"headline\":\"Curso te\u00f3rico-pr\u00e1ctico avanzado: Ecograf\u00eda del nervio perif\u00e9rico en Lleida\",\"datePublished\":\"2026-06-29T15:24:17+00:00\",\"dateModified\":\"2026-06-29T15:24:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/enovis-medtech.eu\\\/es_ES\\\/blog\\\/curso-teorico-practico-avanzado-ecografia-del-nervio-periferico-lleida\\\/\"},\"wordCount\":284,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/enovis-medtech.eu\\\/es_ES\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/enovis-medtech.eu\\\/es_ES\\\/blog\\\/curso-teorico-practico-avanzado-ecografia-del-nervio-periferico-lleida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/enovis-medtech.eu\\\/es_ES\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Imagen-de-WhatsApp-2025-11-17-a-las-10.30.14_f0dd332b-1024x768.jpg\",\"articleSection\":[\"Ecograf\u00eda\",\"Formaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/enovis-medtech.eu\\\/es_ES\\\/blog\\\/curso-teorico-practico-avanzado-ecografia-del-nervio-periferico-lleida\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/enovis-medtech.eu\\\/es_ES\\\/blog\\\/curso-teorico-practico-avanzado-ecografia-del-nervio-periferico-lleida\\\/\",\"url\":\"https:\\\/\\\/enovis-medtech.eu\\\/es_ES\\\/blog\\\/curso-teorico-practico-avanzado-ecografia-del-nervio-periferico-lleida\\\/\",\"name\":\"Curso avanzado: Ecograf\u00eda del nervio perif\u00e9rico en Lleida\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/enovis-medtech.eu\\\/es_ES\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/enovis-medtech.eu\\\/es_ES\\\/blog\\\/curso-teorico-practico-avanzado-ecografia-del-nervio-periferico-lleida\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/enovis-medtech.eu\\\/es_ES\\\/blog\\\/curso-teorico-practico-avanzado-ecografia-del-nervio-periferico-lleida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/enovis-medtech.eu\\\/es_ES\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Imagen-de-WhatsApp-2025-11-17-a-las-10.30.14_f0dd332b-1024x768.jpg\",\"datePublished\":\"2026-06-29T15:24:17+00:00\",\"dateModified\":\"2026-06-29T15:24:19+00:00\",\"description\":\"Curso avanzado: Ecograf\u00eda del nervio perif\u00e9rico en Lleida para mejorar tu diagn\u00f3stico cl\u00ednico con un enfoque pr\u00e1ctico y basado en evidencia.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/enovis-medtech.eu\\\/es_ES\\\/blog\\\/curso-teorico-practico-avanzado-ecografia-del-nervio-periferico-lleida\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/enovis-medtech.eu\\\/es_ES\\\/blog\\\/curso-teorico-practico-avanzado-ecografia-del-nervio-periferico-lleida\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/enovis-medtech.eu\\\/es_ES\\\/blog\\\/curso-teorico-practico-avanzado-ecografia-del-nervio-periferico-lleida\\\/#primaryimage\",\"url\":\"https:\\\/\\\/enovis-medtech.eu\\\/es_ES\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Imagen-de-WhatsApp-2025-11-17-a-las-10.30.14_f0dd332b.jpg\",\"contentUrl\":\"https:\\\/\\\/enovis-medtech.eu\\\/es_ES\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Imagen-de-WhatsApp-2025-11-17-a-las-10.30.14_f0dd332b.jpg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/enovis-medtech.eu\\\/es_ES\\\/blog\\\/curso-teorico-practico-avanzado-ecografia-del-nervio-periferico-lleida\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/enovis-medtech.eu\\\/es_ES\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Curso te\u00f3rico-pr\u00e1ctico avanzado: Ecograf\u00eda del nervio perif\u00e9rico en Lleida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/enovis-medtech.eu\\\/es_ES\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/enovis-medtech.eu\\\/es_ES\\\/blog\\\/\",\"name\":\"Enovis | Blog en Espa\u00f1ol\",\"description\":\"Enovis\u2122 es una empresa de tecnolog\u00eda m\u00e9dica centrada en el desarrollo de soluciones terap\u00e9uticas cl\u00ednicamente diferenciadas que generan resultados significativamente mejores para los pacientes.\",\"publisher\":{\"@id\":\"https:\\\/\\\/enovis-medtech.eu\\\/es_ES\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/enovis-medtech.eu\\\/es_ES\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/enovis-medtech.eu\\\/es_ES\\\/blog\\\/#organization\",\"name\":\"Enovis | Blog en Espa\u00f1ol\",\"url\":\"https:\\\/\\\/enovis-medtech.eu\\\/es_ES\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/enovis-medtech.eu\\\/es_ES\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/enovis-medtech.eu\\\/es_ES\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Enovis_TwoColor-Small-RGB.png\",\"contentUrl\":\"https:\\\/\\\/enovis-medtech.eu\\\/es_ES\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Enovis_TwoColor-Small-RGB.png\",\"width\":1675,\"height\":392,\"caption\":\"Enovis | Blog en Espa\u00f1ol\"},\"image\":{\"@id\":\"https:\\\/\\\/enovis-medtech.eu\\\/es_ES\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/enovis-medtech.eu\\\/es_ES\\\/blog\\\/#\\\/schema\\\/person\\\/a2f1e898e8a22c9e2e223732bdcfcf93\",\"name\":\"Enovis Ib\u00e9rica\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c2992541b710ada9b52a28c2bf1774bacc247004070dcca05b2566d62579d12f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c2992541b710ada9b52a28c2bf1774bacc247004070dcca05b2566d62579d12f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c2992541b710ada9b52a28c2bf1774bacc247004070dcca05b2566d62579d12f?s=96&d=mm&r=g\",\"caption\":\"Enovis Ib\u00e9rica\"},\"sameAs\":[\"http:\\\/\\\/www.enovis-medtech.eu\\\/es_ES\"],\"url\":\"https:\\\/\\\/enovis-medtech.eu\\\/es_ES\\\/blog\\\/author\\\/jordi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Curso avanzado: Ecograf\u00eda del nervio perif\u00e9rico en Lleida","description":"Curso avanzado: Ecograf\u00eda del nervio perif\u00e9rico en Lleida para mejorar tu diagn\u00f3stico cl\u00ednico con un enfoque pr\u00e1ctico y basado en evidencia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/curso-teorico-practico-avanzado-ecografia-del-nervio-periferico-lleida\/","og_locale":"es_ES","og_type":"article","og_title":"Curso avanzado en ecograf\u00eda del nervio perif\u00e9rico en Lleida","og_description":"Curso te\u00f3rico-pr\u00e1ctico avanzado: Ecograf\u00eda del nervio perif\u00e9rico en Lleida para profesionales que buscan mejorar tu diagn\u00f3stico cl\u00ednico con un enfoque pr\u00e1ctico y basado en evidencia.","og_url":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/curso-teorico-practico-avanzado-ecografia-del-nervio-periferico-lleida\/","og_site_name":"Enovis | Blog en Espa\u00f1ol","article_published_time":"2026-06-29T15:24:17+00:00","article_modified_time":"2026-06-29T15:24:19+00:00","og_image":[{"width":350,"height":220,"url":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/wp-content\/uploads\/2026\/03\/Thumbnail.png","type":"image\/png"}],"author":"Enovis Ib\u00e9rica","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Enovis Ib\u00e9rica","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/curso-teorico-practico-avanzado-ecografia-del-nervio-periferico-lleida\/#article","isPartOf":{"@id":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/curso-teorico-practico-avanzado-ecografia-del-nervio-periferico-lleida\/"},"author":{"name":"Enovis Ib\u00e9rica","@id":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/#\/schema\/person\/a2f1e898e8a22c9e2e223732bdcfcf93"},"headline":"Curso te\u00f3rico-pr\u00e1ctico avanzado: Ecograf\u00eda del nervio perif\u00e9rico en Lleida","datePublished":"2026-06-29T15:24:17+00:00","dateModified":"2026-06-29T15:24:19+00:00","mainEntityOfPage":{"@id":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/curso-teorico-practico-avanzado-ecografia-del-nervio-periferico-lleida\/"},"wordCount":284,"commentCount":0,"publisher":{"@id":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/#organization"},"image":{"@id":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/curso-teorico-practico-avanzado-ecografia-del-nervio-periferico-lleida\/#primaryimage"},"thumbnailUrl":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/wp-content\/uploads\/2026\/03\/Imagen-de-WhatsApp-2025-11-17-a-las-10.30.14_f0dd332b-1024x768.jpg","articleSection":["Ecograf\u00eda","Formaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/enovis-medtech.eu\/es_ES\/blog\/curso-teorico-practico-avanzado-ecografia-del-nervio-periferico-lleida\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/curso-teorico-practico-avanzado-ecografia-del-nervio-periferico-lleida\/","url":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/curso-teorico-practico-avanzado-ecografia-del-nervio-periferico-lleida\/","name":"Curso avanzado: Ecograf\u00eda del nervio perif\u00e9rico en Lleida","isPartOf":{"@id":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/curso-teorico-practico-avanzado-ecografia-del-nervio-periferico-lleida\/#primaryimage"},"image":{"@id":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/curso-teorico-practico-avanzado-ecografia-del-nervio-periferico-lleida\/#primaryimage"},"thumbnailUrl":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/wp-content\/uploads\/2026\/03\/Imagen-de-WhatsApp-2025-11-17-a-las-10.30.14_f0dd332b-1024x768.jpg","datePublished":"2026-06-29T15:24:17+00:00","dateModified":"2026-06-29T15:24:19+00:00","description":"Curso avanzado: Ecograf\u00eda del nervio perif\u00e9rico en Lleida para mejorar tu diagn\u00f3stico cl\u00ednico con un enfoque pr\u00e1ctico y basado en evidencia.","breadcrumb":{"@id":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/curso-teorico-practico-avanzado-ecografia-del-nervio-periferico-lleida\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/enovis-medtech.eu\/es_ES\/blog\/curso-teorico-practico-avanzado-ecografia-del-nervio-periferico-lleida\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/curso-teorico-practico-avanzado-ecografia-del-nervio-periferico-lleida\/#primaryimage","url":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/wp-content\/uploads\/2026\/03\/Imagen-de-WhatsApp-2025-11-17-a-las-10.30.14_f0dd332b.jpg","contentUrl":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/wp-content\/uploads\/2026\/03\/Imagen-de-WhatsApp-2025-11-17-a-las-10.30.14_f0dd332b.jpg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/curso-teorico-practico-avanzado-ecografia-del-nervio-periferico-lleida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/"},{"@type":"ListItem","position":2,"name":"Curso te\u00f3rico-pr\u00e1ctico avanzado: Ecograf\u00eda del nervio perif\u00e9rico en Lleida"}]},{"@type":"WebSite","@id":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/#website","url":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/","name":"Enovis | Blog en Espa\u00f1ol","description":"Enovis\u2122 es una empresa de tecnolog\u00eda m\u00e9dica centrada en el desarrollo de soluciones terap\u00e9uticas cl\u00ednicamente diferenciadas que generan resultados significativamente mejores para los pacientes.","publisher":{"@id":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/#organization","name":"Enovis | Blog en Espa\u00f1ol","url":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/wp-content\/uploads\/2024\/08\/Enovis_TwoColor-Small-RGB.png","contentUrl":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/wp-content\/uploads\/2024\/08\/Enovis_TwoColor-Small-RGB.png","width":1675,"height":392,"caption":"Enovis | Blog en Espa\u00f1ol"},"image":{"@id":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/#\/schema\/person\/a2f1e898e8a22c9e2e223732bdcfcf93","name":"Enovis Ib\u00e9rica","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c2992541b710ada9b52a28c2bf1774bacc247004070dcca05b2566d62579d12f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c2992541b710ada9b52a28c2bf1774bacc247004070dcca05b2566d62579d12f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c2992541b710ada9b52a28c2bf1774bacc247004070dcca05b2566d62579d12f?s=96&d=mm&r=g","caption":"Enovis Ib\u00e9rica"},"sameAs":["http:\/\/www.enovis-medtech.eu\/es_ES"],"url":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/author\/jordi\/"}]}},"_links":{"self":[{"href":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/wp-json\/wp\/v2\/posts\/2378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/wp-json\/wp\/v2\/comments?post=2378"}],"version-history":[{"count":5,"href":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/wp-json\/wp\/v2\/posts\/2378\/revisions"}],"predecessor-version":[{"id":2409,"href":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/wp-json\/wp\/v2\/posts\/2378\/revisions\/2409"}],"wp:attachment":[{"href":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/wp-json\/wp\/v2\/media?parent=2378"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/wp-json\/wp\/v2\/categories?post=2378"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/enovis-medtech.eu\/es_ES\/blog\/wp-json\/wp\/v2\/tags?post=2378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}